{"id":1967,"date":"2021-12-29T08:01:47","date_gmt":"2021-12-29T08:01:47","guid":{"rendered":"https:\/\/www.semjoncontemporary.com\/2022\/?post_type=ausstellungen&#038;p=1967"},"modified":"2022-02-01T22:14:14","modified_gmt":"2022-02-01T22:14:14","slug":"2013-mad-odor-roses","status":"publish","type":"ausstellungen","link":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/","title":{"rendered":"2013 \u2013 mad odor roses"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;3.22&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_gallery gallery_ids=&#8220;1970,1971,1972,1968&#8243; _builder_version=&#8220;4.14.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_gallery][et_pb_blog include_categories=&#8220;30&#8243; _builder_version=&#8220;4.14.7&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blog][et_pb_text _builder_version=&#8220;4.14.7&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>Michael Kutschbachs \u2013\u00a0mad odor roses<\/strong><\/p>\n<p><em><strong>Fix und Flux<\/strong><\/em><\/p>\n<p>Schwebend, ohne Fundament pr\u00e4sentieren sich die Formballungen der Fotoserie <em>mad odor roses<\/em> (2013) von Michael Kutschbach. Sie sind Resultate eines gegl\u00fcckten Moments, in dem sich Blickwinkel, Beleuchtung und atmosph\u00e4rische Absichten zu einer harmonischen Bildganzheit f\u00fcgen und sich k\u00fcnstlerischer Gestaltungswille in h\u00f6chster Verdichtung manifestiert. Kristallines in alabasterfarbener Eleganz gesellt sich neben Biomorphem in strahlender Farbopulenz, ein M\u00f6biusband umschlingt organisch anmutende Konglomerate in metallischer Mattheit, und Konstruktionen in technoider Pr\u00e4zision verbinden sich mit oberfl\u00e4chigen Unebenheiten, Verl\u00e4ufen und Eintr\u00fcbungen. Als \u201eKombinationen aus Faustkeil und Weltraumschrott\u201c mag der Betrachter diese Formationen wahrnehmen und sie zwischen \u201eeinem kulturellen Hochgef\u00fchl und dem Erlebnis der Deformation\u201c ansiedeln,<a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftn1\" name=\"_ftnref1\">[1]<\/a> und doch entziehen sie sich der Wiedererkennbarkeit und dokumentieren vielmehr die Lust an der spielerisch-explorativen Erkundung unbestimmten Formenterrains.<\/p>\n<p>Setzt Kutschbach in seinen Studioaufnahmen Licht wie bei einer Portr\u00e4taufnahme ein, um den Gebilden ihr jeweils unverwechselbares \u00b4Gesicht\u00b4 zu verleihen \u2013 von weich gestreut durch Frontallicht bis modulierend durch seitliche Punktstrahler \u2013 so soll der Betrachter indes nicht \u00fcber den Effekt in die illusionistische Falle gelockt werden. Was wir hier sehen ist Handwerk im w\u00f6rtlichen Sinne: So wenig die Fotografien im Nachgang digital bearbeitet sind und sich alleine der aufnahmetechnischen Versiertheit verdanken, so sehr sind auch ihre Bildgegenst\u00e4nde das Ergebnis plastischer Handarbeit. Der K\u00fcnstler hat sie als autonome Kleinplastiken geschaffen, teils aus Gips geformt, teils aus verschiedenen Materialien \u2013 Schaum, gefundenen Objekten, Klebstoffen und den Hinterlassenschaften gro\u00dfz\u00fcgiger Farb\u00fcberz\u00fcge \u2013 zu kompakten, hier zentral in den Blick ger\u00fcckten Unikaten zusammengef\u00fcgt. Vergegenw\u00e4rtigt man sich die haptische Qualit\u00e4t der Plastiken in ihrer Dreidimensionalit\u00e4t, so vermag auch das Atmosph\u00e4rische zu Leben erweckt werden, das in Form wabernder Nebelschwaden ein Moment des Diffusen und Enigmatischen erzeugt, wenn nicht gar eine Irritation beim Betrachter hervorruft. Dieses Moment des Zusammentreffens disparater Zust\u00e4nde, wenn sich Festes und Unbewegtes mit Gasf\u00f6rmigem, Bewegtem amalgamiert und der jeweils eine Zustand zum integralen Bestandteil des anderen wird, hat Kutschbach buchst\u00e4blich festgehalten, indem er ihn in den zweidimensionalen Bildtr\u00e4ger gebannt hat.<\/p>\n<p>Als singul\u00e4re Ensembles sinnlich eindr\u00fccklicher Ph\u00e4nomene beruhen die so fixierten Erscheinungsbilder auf unwiederholbaren Inszenierungen. Die Konturlosigkeit und Unkontrollierbarkeit des Dampfes und seine Verfl\u00fcchtigung im Raum verst\u00e4rkt rein visuell den Schwebezustand des festen Materials. Und hier kommt nun doch die Illusion ins Spiel. Der K\u00fcnstler f\u00fchrt uns beil\u00e4ufig und bildhaft vor Augen, was das Bild als solches zu leisten vermag und was der Tr\u00e4gheit der Plastik verwehrt bleibt: die Aufhebung der Schwerkraft. Die Unwiederholbarkeit der Inszenierung wie auch die Unantastbarkeit des ephemeren Stoffs wird dabei mit ihrer fotografischen Fixierung durchkreuzt. Experimentiert hat Kutschbach mit den Potenzialen des Ephemeren bereits in fr\u00fcheren Arbeiten, etwa in der Videoarbeit <em>gimble in the wabe<\/em> (2011), in dem die Eigenheiten des sich verfl\u00fcchtigenden Stoffes mit den filmischen Techniken der Verlangsamung und Beschleunigung visuell in die Dimension der Zeit eingebettet wird.<a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftn2\" name=\"_ftnref2\">[2]<\/a><\/p>\n<p>Seit den sp\u00e4ten 1960er Jahren geh\u00f6rt die Auseinandersetzung mit den Aggregatzust\u00e4nden zum etablierten und programmatischen Repertoire k\u00fcnstlerischer Fragestellungen. Die Verwandlungen und R\u00fcckverwandlungen von Erstarrtem in Flie\u00dfendes, von Kaltem in Warmes, von Anorganischem in Organisches, von Ungeformtem in Geformtes haben vielgestaltige k\u00fcnstlerische Ausdrucksweisen gefunden. Sie befragen im Hin- und Herpendeln zwischen dem Ephemeren und dem Konkreten die existenziellen und materialen Prozesse von \u00dcberg\u00e4ngen und Metamorphosen. Bekanntlich wurden die Dampfinstallationen von Robert Morris 1967 nicht zur <em>New York Sculpture Exhibition<\/em>zugelassen, weil sie mit ihrem Anti-Form-Konzept nicht der g\u00e4ngigen Vorstellung der Bildhauerei entsprachen. 1984 installierte Joseph Beuys indes sein <em>Thermisch-plastisches Urmeter<\/em> in der Baseler Ausstellung <em>Skulptur im 20. Jahrhundert<\/em>. Die dynamischen und energetischen Aspekte von Dampf sollte er dabei als Metapher f\u00fcr das Denken begreifen und in seine Idee der sozialen Plastik integrieren.<a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftn3\" name=\"_ftnref3\">[3]<\/a> Der Einsatz des Gasf\u00f6rmigen war und ist vornehmlich f\u00fcr jene K\u00fcnstler von Bedeutung, die die traditionellen Bildgattungen verlassen und eine prozessuale, vom Material her bestimmte Kunst entwickeln. Dampf erscheint als \u201eintelligenter\u201c Stoff, weil er seine Volumenbildung ganz ohne k\u00fcnstlerisches Zutun entfaltet und dar\u00fcber hinaus die traditionelle Priorisierung der Form \u00fcberwindet.<\/p>\n<p>Das Prozessuale geh\u00f6rt auch in Michael Kutschbachs k\u00fcnstlerischer Arbeit zu den elementaren Prinzipien, wenn n\u00e4mlich transformative Kr\u00e4fte verwendeter Materialien und Oberfl\u00e4chen visualisiert werden. Weniger als Kreator seiner Werke verstehe er seine Rolle als K\u00fcnstler, als vielmehr als Initiator selbst ablaufender, produktiver Vorg\u00e4nge.<a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftn4\" name=\"_ftnref4\">[4]<\/a>In einem eigenen Werkkomplex, den Zeichnungen, wird das Flie\u00dfen und Arretieren im steten Changieren zwischen Formverweigerung und Formfindung zum <em>modus operandi<\/em>. Die \u201eProzesszeichnungen\u201c, wie Kutschbach sie nennt, sind Resultate des Zeichnens, Verwischens, Ausradierens, Kratzens, Schabens und steten \u00dcberzeichnens in einer Art und Weise, dass die vorg\u00e4ngigen Linien sichtbar bleiben, vielleicht einem Palimpsest vergleichbar, bei dem die Spuren des Originaltextes erhalten geblieben sind. Der Prozess des beharrlichen Aufbringens und L\u00f6schens von Linien, Konturen und Schattierungen entspringt weniger einer obsessiv-aggressiven Geste als vielmehr einer arch\u00e4ologischen Praxis, mit deren langwierigen Arbeitsvorg\u00e4ngen die zuletzt gefundene Form aus den unbewussten Schichten des K\u00fcnstlers gleichsam herausgesch\u00e4lt wird. Wie in Ausgrabungen die durch Erosion und tektonische Einbr\u00fcche geformten Gesteinsschichten Vorhergegangenes sichtbar werden lassen, f\u00fchren die Kratzspuren und vorg\u00e4ngigen Linien auf den Bl\u00e4ttern gleich Pfaden zu einem unersch\u00f6pflichen Formenfundus. Auch hier geht es wieder um die Bannung des Ephemeren und Transitorischen ins Bild, um die allm\u00e4hliche Verwandlung von Grafitstaub in wundersam-schnittige und elegante Formverdichtungen, die in ihrer Pr\u00e4zision und Klarheit wie Fragmente gr\u00f6\u00dferer Zusammenh\u00e4nge in die Welt gekommen sind.<\/p>\n<p>Pr\u00e4senz und Verschwinden sind mithin Komponenten in der Pr\u00e4sentationsweise der Serie <em>mad odor roses<\/em>. Auf drei mal drei Meter gro\u00dfe Wandtapeten, die in ausschnitthaften Vergr\u00f6\u00dferungen das faszinierende Formenrepertoire seiner plastischen Objekte n\u00e4her an das Betrachterauge heranr\u00fccken, hat Kutschbach sie geh\u00e4ngt. Das Bild auf dem Bild verliert in camouflierender Wirkung zwar seine Pr\u00e4gnanz. Im Mit- und Zueinander von Ganzem und Detail und ihrem ph\u00e4nomenalen Zusammenwirken widerstrebt die Installation allerdings avantgardistischen \u00dcberzeugungen, wonach Ganzheiten anschaulich nicht mehr gegeben sind. Mikro- und Makrobild haben in Kutschbachs Arbeiten verweisenden Charakter. Die Gestaltung von Raumsituationen, in denen sich kleinformatige Zeichnungen in ihren gigantisch vergr\u00f6\u00dferten Widerparts auf W\u00e4nden wiederfinden, in denen raumf\u00fcllende Wandverkleidungen, die nah am Dekorativen und Ornamentalen Figurenwelten plastischer Arbeiten aufgreifen und \u2013 wie in der aktuellen Arbeit \u2013 in denen Fototapeten, die alleine durch ihre schiere Gr\u00f6\u00dfe zu einem Eintreten in das Werk einladen, implizieren zugleich das Heraustreten aus dem Bild, das Zur\u00fccktreten vor dem Werk und die Distanznahme zum Medium, denn nur so k\u00f6nnen Teil und Ganzes erfahren werden.<\/p>\n<p>Zum \u201ework in progress\u201c geh\u00f6ren auch Titelfindungen, die Paul Klee mit ihren evokativen und vieldeutigen Bedeutungs\u00fcberg\u00e4ngen einmal treffend als \u201esprachliche Schwebungen\u201c bezeichnet hat. Und so appelliert auch der widersinnige Titel <em>mad odor roses<\/em> nicht etwa an die olfaktorische Wahrnehmung des Betrachters, sondern dient der poetisch-humorvollen Verschl\u00fcsselung. Die Serie ist eine Hommage an einen K\u00fcnstler, dessen Name sich anagrammatisch in der Titulierung verbirgt: Medardo Rosso. Die Aufhebung der Gattungsgrenzen zwischen Malerei, Skulptur und Fotografie kennzeichnet das k\u00fcnstlerische Schaffen des italienischen Bildhauers, dessen Ringen um einen stimmigen Ausdruck f\u00fcr die Fl\u00fcchtigkeit von Erscheinungen ein grandioses Gesamt\u0153uvre hervorgebracht hat. Scheinbar schwebende, konturlose Portr\u00e4ts und nahezu in Aufl\u00f6sung begriffene Bildnisk\u00f6pfe bev\u00f6lkern das Gestaltenpantheon Rossos, w\u00e4hrend sich die bildhafte Verschmelzung von Figur und Raum kontrapunktisch in seinen Fotografien ereignet. Kutschbach bringt eine weitere Referenzfigur f\u00fcr seine Werke ins Spiel, wenn er in gleicher Weise die Tituli der einzelnen Fotografien wohlklingend komponiert: <em>Strong-Minded Kiosk Roach<\/em>, <em>Thick-Skinned Orgasm Odor<\/em>, <em>Rest Room Dockhand Skiing<\/em> usw. Auch sie sind Anagramme, entwickelt aus den beiden Namen Medardo Rosso und Nick Knight. Ekstatisch und exzentrisch sind die Modefotografien Knights, das Moment des Transitorischen verbindet ihn wiederum mit dem Pionier der Moderne. Kutschbachs Titel entspringen der Lust des K\u00fcnstlers an alogischen Kalauern, Nonsense-Gedichten und Palindromen und lassen mit dem \u00fcberbordenden Ertrag entfesselten Fabulierens eine scheinbare Systematik entstehen. Alles andere als explikatorische Absichten stecken hinter diesen Werktiteln, sie fungieren vielmehr als Parallelen zum bildnerischen Werk und weisen auf die Unm\u00f6glichkeit, sich, sein Werk oder Kunst schlechthin zu erkl\u00e4ren.<\/p>\n<p>Was in Michael Kutschbachs Arbeiten zusammenwirkt, ist dialektisch auf verschiedenen Ebenen: Formbares und Formloses, Spontanes und Konzeptuelles, Fassbares und Unfassbares, Sinnliches und Begriffliches, Intuition und Ratio. Die M\u00f6glichkeit der Kunst, die Dinge zu verkehren, Gegenstrebiges zusammenzuf\u00fcgen und Zust\u00e4nde zu transformieren, ist in seinem Werk mit einer Klarheit, Stille und Tiefe verbunden, die den Betrachter f\u00fcr Momente in Regionen des Kontemplativen und der Unbeschwertheit zu geleiten verm\u00f6gen.<br \/>Judith Elisabeth Weiss<\/p>\n<p><a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftnref1\" name=\"_ftn1\">[1]<\/a> Vgl. Christoph Tannert, \u201eHarmonieentw\u00fcrfe in Mikro und Makro\u201c, in: Michael Kutschbach, <em>Callooh! Callay!<\/em>, Ausst. Kat. K\u00fcnstlerhaus Bethanien, Berlin 2010, o. S.<\/p>\n<p><a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftnref2\" name=\"_ftn2\">[2]<\/a> Siehe zu dieser Video-Arbeit das Interview mit Michael Kutschbach in: <em>Sculpture and the Enemies Magazine<\/em>, Juli-September 2011, Sydney, S. 28-32.<\/p>\n<p><a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftnref3\" name=\"_ftn3\">[3]<\/a> Siehe Theodora Vischer, \u201eJoseph Beuys. Thermisch-plastisches Urmeter \u2013 ein Sp\u00e4twerk\u201c, in: Volker Harlan u.a. (Hg.), <em>Joseph Beuys-Tagung<\/em>, Basel 1991, S. 214-219.<\/p>\n<p><a href=\"applewebdata:\/\/4A70A6FE-03A4-4D78-AEC5-DBFF8B06F561#_ftnref4\" name=\"_ftn4\">[4]<\/a> Siehe zum Aspekt der Transformation Varga Hosseini, \u201eSurface in Flux: Michael Kutschbach\u201c, in: <em>Australian Art Collector<\/em>, Issue 34 (Oktober\/November), Sydney 2005, S. 241; zur Rolle des K\u00fcnstlers siehe Interview (wie Anm. 2).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"featured_media":1968,"parent":0,"menu_order":115,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[30],"class_list":["post-1967","ausstellungen","type-ausstellungen","status-publish","has-post-thumbnail","hentry","category-michael-kutschbach-ausstellungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2013 \u2013 mad odor roses - Semjon Contemporary<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2013 \u2013 mad odor roses - Semjon Contemporary\" \/>\n<meta property=\"og:description\" content=\"Michael Kutschbachs \u2013\u00a0mad odor roses Fix und Flux Schwebend, ohne Fundament pr\u00e4sentieren sich die Formballungen der Fotoserie mad odor roses (2013) von Michael Kutschbach. Sie sind Resultate eines gegl\u00fcckten Moments, in dem sich Blickwinkel, Beleuchtung und atmosph\u00e4rische Absichten zu einer harmonischen Bildganzheit f\u00fcgen und sich k\u00fcnstlerischer Gestaltungswille in h\u00f6chster Verdichtung manifestiert. Kristallines in alabasterfarbener Eleganz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/\" \/>\n<meta property=\"og:site_name\" content=\"Semjon Contemporary\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/semjon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-01T22:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/12\/yellow-02_MK_2000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/\",\"name\":\"2013 \u2013 mad odor roses - Semjon Contemporary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/yellow-02_MK_2000.jpg\",\"datePublished\":\"2021-12-29T08:01:47+00:00\",\"dateModified\":\"2022-02-01T22:14:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/yellow-02_MK_2000.jpg\",\"contentUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/yellow-02_MK_2000.jpg\",\"width\":2000,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/ausstellungen\\\/2013-mad-odor-roses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2013 \u2013 mad odor roses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\",\"name\":\"Semjon Contemporary\",\"description\":\"Galerie f\u00fcr zeitgen\u00f6ssische Kunst\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#organization\",\"name\":\"Semjon Contemporary\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/SC-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/SC-logo.png\",\"width\":2221,\"height\":512,\"caption\":\"Semjon Contemporary\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/semjon\\\/\",\"https:\\\/\\\/www.instagram.com\\\/semjoncontemporary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2013 \u2013 mad odor roses - Semjon Contemporary","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/","og_locale":"de_DE","og_type":"article","og_title":"2013 \u2013 mad odor roses - Semjon Contemporary","og_description":"Michael Kutschbachs \u2013\u00a0mad odor roses Fix und Flux Schwebend, ohne Fundament pr\u00e4sentieren sich die Formballungen der Fotoserie mad odor roses (2013) von Michael Kutschbach. Sie sind Resultate eines gegl\u00fcckten Moments, in dem sich Blickwinkel, Beleuchtung und atmosph\u00e4rische Absichten zu einer harmonischen Bildganzheit f\u00fcgen und sich k\u00fcnstlerischer Gestaltungswille in h\u00f6chster Verdichtung manifestiert. Kristallines in alabasterfarbener Eleganz [&hellip;]","og_url":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/","og_site_name":"Semjon Contemporary","article_publisher":"https:\/\/www.facebook.com\/semjon\/","article_modified_time":"2022-02-01T22:14:14+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/12\/yellow-02_MK_2000.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/","url":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/","name":"2013 \u2013 mad odor roses - Semjon Contemporary","isPartOf":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/#primaryimage"},"image":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/12\/yellow-02_MK_2000.jpg","datePublished":"2021-12-29T08:01:47+00:00","dateModified":"2022-02-01T22:14:14+00:00","breadcrumb":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/#primaryimage","url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/12\/yellow-02_MK_2000.jpg","contentUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/12\/yellow-02_MK_2000.jpg","width":2000,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/www.semjoncontemporary.com\/2022\/ausstellungen\/2013-mad-odor-roses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.semjoncontemporary.com\/2022\/"},{"@type":"ListItem","position":2,"name":"2013 \u2013 mad odor roses"}]},{"@type":"WebSite","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#website","url":"https:\/\/www.semjoncontemporary.com\/2022\/","name":"Semjon Contemporary","description":"Galerie f\u00fcr zeitgen\u00f6ssische Kunst","publisher":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.semjoncontemporary.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#organization","name":"Semjon Contemporary","url":"https:\/\/www.semjoncontemporary.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/11\/SC-logo.png","contentUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/11\/SC-logo.png","width":2221,"height":512,"caption":"Semjon Contemporary"},"image":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/semjon\/","https:\/\/www.instagram.com\/semjoncontemporary"]}]}},"_links":{"self":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/ausstellungen\/1967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/ausstellungen"}],"about":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/types\/ausstellungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/media\/1968"}],"wp:attachment":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/media?parent=1967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semjoncontemporary.com\/2022\/wp-json\/wp\/v2\/categories?post=1967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}