{"id":3924,"date":"2022-06-06T15:07:13","date_gmt":"2022-06-06T15:07:13","guid":{"rendered":"https:\/\/www.semjoncontemporary.com\/2022\/?post_type=ausstellungen&#038;p=3924"},"modified":"2024-11-12T14:20:39","modified_gmt":"2024-11-12T14:20:39","slug":"bildtafel-tafelbild","status":"publish","type":"ausstellungen","link":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/","title":{"rendered":"2019 \u2013 Klaus Steinmann"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_gallery gallery_ids=&#8220;3914,3915,3916,3917,3919,3918,3913&#8243; posts_number=&#8220;24&#8243; _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_gallery][et_pb_text _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p style=\"font-weight: 400;\"><strong><em>Tafelbild \u2013 Bildtafel<br \/><\/em><\/strong><strong>Klaus Steinmann<br \/><\/strong><br \/>9.2. \u2013 16.3.2019<\/p>\n<p style=\"font-weight: 400;\"><em>Im Grenzbereich der Malerei \u2013 <br \/>Malerei und Plastik bedingen sich im Werk von Klaus Steinmann<\/em><\/p>\n<p>In seiner ersten Einzelausstellung bei Semjon Contemporary zeigt Klaus Steinmann Werke der letzten Jahre.<br \/>Zuvor hatte er 2016 zusammen mit Colin Ardley die Dialogausstellung durchgef\u00fchrt und war 2017 beteiligt an der Galerie-Gruppenausstellung <em>Penetrating Paper: Gebohrt, Geschnitten, Gefaltet&#8230;<\/em> Zwischendurch sind seine Werke ebenfalls in einigen Accrochage-Ausstellungen sowie Salon-H\u00e4ngungen zu sehen gewesen. Klaus Steinmann ist also mit seinem Werk l\u00e4ngst eingef\u00fchrt in den Kanon der Galeriek\u00fcnstler und Kreis der Galeriefreunde.<\/p>\n<p>Rund 30 Jahre lang wurde der K\u00fcnstler von der renommierten, auf Konkrete Kunst spezialisierten Galerie Walzinger aus Saarlois vertreten (u.a. zusammen mit Hartmut B\u00f6hme, Leo Erb und Eva Niesrath). Mit dem Tod des Galeristen 2014 wurde auch die Galerie geschlossen.<br \/>1981 konnte Klaus Steinmann im Neuen Berliner Kunstverein in einer Einzelausstellung sein bis dato geschaffenes Werk vorstellen. 1992 und 1994 folgten sp\u00e4ter Einzelausstellungen im Wilhelm-Hack-Museum in Ludwigshafen und im Kunstverein Augsburg.<\/p>\n<p>Von der geometrischen Strenge seiner fr\u00fcheren, oft gro\u00dfformatigen Werke hat der K\u00fcnstler sich schon lange verabschiedet. Die Konkrete Kunst, die seit den 50er bis in die sp\u00e4ten 80er Jahre erbitterte Richtungsstreitereien durchlebte und f\u00fcr den K\u00fcnstler nicht unwichtig aber auch nicht das Nonplusultra war, hatte sich \u00fcber die Jahrzehnte \u00f6ffnen m\u00fcssen. Noch 2013, als ich mit den Galeriek\u00fcnstlern Colin Ardley, Dirk Rathke und Dittmar Kr\u00fcger auf Einladung des Forum f\u00fcr Konkrete Kunst in Erfurt beim Kolloquium <em>Blick zur\u00fcck und voraus<\/em> ein Gespr\u00e4ch \u00fcber die sich notwendig aufl\u00f6senden Grenzen der Konkreten Kunst \u2013 zum Schutz ihrer selbst willen \u2013 thematisierte, bekamen wir im Auditorium mit, dass es noch \u201aknisterte\u2018.* F\u00fcr Klaus Steinmann waren aber auch das amerikanische Colorfield Painting (Farbfeld-Malerei) sowie die Minimal Art wichtig.<\/p>\n<p style=\"font-weight: 400;\">Der K\u00fcnstler hat sich in den letzten Jahren vorwiegend auf kleinere Formate konzentriert. Das erm\u00f6glicht ihm, sich t\u00e4glich in seiner Atelierwohnung in Berlin oder in Walsrode mit den immer wiederkehrenden Themen der Geometrie, den Grundformen des Recht- und Dreiecks sowie des Kreises zu besch\u00e4ftigen. Und zwar geschieht dies im Spannungsfeld seiner Erfahrung aus der hohen Zeit der Konkreten Kunst und der \u00dcberwindung ihres strikten Regulariums. Augenzwinkernd konterkariert er diesen strengen Geist, um weiter zu wachsen, neue M\u00f6glichkeiten und ihre Grenzen auszuloten. Das gelingt ihm auf subtile und erfrischende Art und Weise. Der K\u00fcnstler baut sich selbst kleine H\u00fcrden, um das Glatte, das Berechenbare zu umgehen: Auf die Holztafel, zumeist sind es d\u00fcnne Birkensperrholzplatten, zieht er einen Leinwandstoff oder grobes Tuch auf. Die Struktur des Materials ist evident, gemahnt an Leinwand, doch erm\u00f6glicht ihm das Material Sperrholz die plane Fl\u00e4che skulptural aufzubrechen, und zwar in der Art, dass z.B. ein monochrom aufgemaltes Quadrat oder Hochrechteck durch das Aufs\u00e4gen der Silhouette dieser Form gezielt aus der Ebene der Leinwand nach vorne kippt und sein Pendent, die andere H\u00e4lfte, in die Tiefe geht. Dadurch entsteht ein verbl\u00fcffendes Vexierspiel von Vorne und Hinten und erlaubt einem weiteren hinzugewonnenen Akteur seiner Malerei, dem Schatten, die strenge Geometrie der gemalten Formen aufzubrechen, ihnen eine zarte Modulation einzuhauchen. Gleichzeitig werden die vorkragenden Kanten, so Licht darauf f\u00e4llt, optisch erh\u00f6ht, weil des Wei\u00df dort wei\u00dfer ist als der allgemeine wei\u00dfe Malgrund. Das gesamte Tafelbild oder die Bildtafel wird subtil und spielerisch belebt.<br \/>Dem K\u00fcnstler ist \u00fcbrigens die Eigenwilligkeit der d\u00fcnnen Birkenholzplatten sympathisch. Dass sich die Tafeln mitunter verziehen, st\u00f6rt ihn partout nicht. Im Gegenteil: Er nimmt das Holzverhalten mit Humor und erfreut sich an seiner Individualit\u00e4t, seiner Nicht-Z\u00e4hmbarkeit.<\/p>\n<p>Wenn man sich die Geschichte des (abendl\u00e4ndlichen) Tafelbildes vergegenw\u00e4rtigt, als noch urspr\u00fcnglich die Malerei auf eine Holztafel aufgebracht wurde, und dann auch von ihrer Kontextualisierung wei\u00df und dem Einbau dieser in ein Rahmenwerk eines z.B. fr\u00fchen christlichen Altars \u2013 fixiert mittels kleiner Holzriegel, dann bekommen die Tafelbilder von Klaus Steinmann einen zus\u00e4tzlichen augenzwinkernden Twist. Die R\u00fcckseiten seiner Gewerke sind ein zus\u00e4tzliches augenfreundliches Vergn\u00fcgen: Die nach vorne oder hinten klappenden Fl\u00e4chen werden n\u00e4mlich durch kleine zarte, eingeleimte Riegelchen fixiert, die je nach Komposition des Bildes mit seinen geometrischen Grundformen ein zus\u00e4tzliches spannungsreiches Spiel vorf\u00fchren. Synchron zum einzelnen Altarbild im Gesamtgef\u00fcge eines Altars, sind seine gemalten und gekippten Einzelformen im sehr frei \u00fcbertragenen Sinne die Altarbilder. Erst sie gemeinsam erg\u00e4nzen sich zum Gro\u00dfen und Ganzen eines einzelnen Bildes, wie die einzelnen Altarbilder die Heilsgeschichte Christi in einzelnen Bildern zur gro\u00dfen Erz\u00e4hlung aufschl\u00fcsseln.<\/p>\n<p>In ganz neuen Werken erlaubt sich der K\u00fcnstler ein weiteres St\u00fcck Freiheit. Die Spannung zwischen der geometrischen, monochromen Form und einer neu hinzukommenden biomorphen Struktur wird zum Thema. Auf schr\u00fcndiger und rissiger, wei\u00df gefasster Birkensperrholzoberfl\u00e4che, dieses Mal nicht mit Tuch bespannt, werden die dem Material geschuldeten Erhebungen wie bei einer H\u00f6henlandkarte zur Herausforderung: Die strenge geometrische Form wird an ihren Kanten gem\u00e4\u00df dem Verlauf der Holzmaserung aufgebrochen. Nur bestimmte Perspektiven erlauben die Klarheit der strengen Form. Von anderen Standpunkten aus gesehen treppt sich pl\u00f6tzlich die Silhouettenlinie, wird zum humorvollen Kommentar des K\u00fcnstlers.<\/p>\n<p>Der Maler Klaus Steinmann ist aber auch ein Freund des Dreidimensionalen. Dies bezeugen die kleinen Objekte oder auch H\u00e4ngeobjekte seit den 70er Jahren, die allesamt auch als Modelle f\u00fcr gr\u00f6\u00dfere Skulpturen fungieren k\u00f6nnten. <br \/>Mit sparsamen Eingriffen durch Einschnitte und Faltungen wird eine einfache Form, z.B. die eines Kreises, oder eines Ovals in ein komplexes, in alle Richtung weisendes Objekt verwandelt, das sich durch gezielt eingesetzte Farbfassungen in unterschiedlicher Form und Farbgestalt offenbart. Eines seiner neuesten Objekte, direkt f\u00fcr die horizontale Nische im Stra\u00dfen-Salon geschaffen, verbl\u00fcfft einmal mehr durch die Ausgewogenheit von Form und Farbe zu einem irritierenden, weil horizontal ausgerichteten Objekt, das in seiner Form an eine liegende, geometrisierende Acht erinnert. Es ist die Teilfl\u00e4che eines Ovals, gefaltet um eine Achse, aufgebrochen durch eine ausgeschnittene Binnenfl\u00e4che und partiell mit einem Kadmiumgelb und einem warmen Kadmiumrot bemalt. Die Faltung (eigentlich ist es keine Faltung, denn das Material ist Sperrholz, also sind die Fl\u00e4chen winkelig zueinander verleimt) verursacht in unserem Gehirn, dass die eigentlich simple Form kompliziert wird. Hier zeigt sich, dass der Maler ausgesprochen dreidimensional denken kann, was ja in seiner Malerei bereits fassbar ist. Der humorvolle Charakter des K\u00fcnstlers offenbart sich zudem auch in einer weiteren beabsichtigten Objekteigenschaft: Es ist ein Wipp-Objekt!<br \/>Seine vertikal ausgerichteten Objekte, mal auf einem kleinen Holzsockel, mal als H\u00e4ngeobjekt konzipiert, atmen den gleichen Geist zauberhafter Eleganz. Die einfache Form, geschickt um eine Achse \u201agefaltet\u2018, versehen mit einem ausgeschnittenen Negativraum und dann auf jeder Seite andersfarbig bemalt (hier wird auch das Wei\u00df zur Farbe!) inhaliert die Geschichte der konstruktiven Plastik im Allgemeinen und atmet frisch das Heutige in seiner Ambivalenz aus. Das gleiche l\u00e4sst sich zu seiner Malerei sagen. Deswegen ist Klaus Steinmann, wenn auch urspr\u00fcnglich von der Konstruktiven Kunst nicht unber\u00fchrt, absolut im Heute schaffend und lebend, frisch und frei!<\/p>\n<p>Semjon H. N. Semjon<br \/>Januar\/Februar 2019<\/p>\n<p style=\"font-weight: 400;\">*Leider ist diese Institution inzwischen geschlossen worden. Die Kunst wird in Erfurt gar stiefm\u00fctterlich behandelt! <\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"featured_media":3914,"parent":0,"menu_order":59,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[110],"class_list":["post-3924","ausstellungen","type-ausstellungen","status-publish","has-post-thumbnail","hentry","category-klaus-steinmann-ausstellungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2019 \u2013 Klaus Steinmann - Semjon Contemporary<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2019 \u2013 Klaus Steinmann - Semjon Contemporary\" \/>\n<meta property=\"og:description\" content=\"Tafelbild \u2013 BildtafelKlaus Steinmann9.2. \u2013 16.3.2019 Im Grenzbereich der Malerei \u2013 Malerei und Plastik bedingen sich im Werk von Klaus Steinmann In seiner ersten Einzelausstellung bei Semjon Contemporary zeigt Klaus Steinmann Werke der letzten Jahre.Zuvor hatte er 2016 zusammen mit Colin Ardley die Dialogausstellung durchgef\u00fchrt und war 2017 beteiligt an der Galerie-Gruppenausstellung Penetrating Paper: Gebohrt, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/\" \/>\n<meta property=\"og:site_name\" content=\"Semjon Contemporary\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/semjon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T14:20:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2022\/06\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/\",\"name\":\"2019 \u2013 Klaus Steinmann - Semjon Contemporary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg\",\"datePublished\":\"2022-06-06T15:07:13+00:00\",\"dateModified\":\"2024-11-12T14:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg\",\"contentUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/en\\\/ausstellungen\\\/bildtafel-tafelbild\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2019 \u2013 Klaus Steinmann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\",\"name\":\"Semjon Contemporary\",\"description\":\"Galerie f\u00fcr zeitgen\u00f6ssische Kunst\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#organization\",\"name\":\"Semjon Contemporary\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/SC-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/SC-logo.png\",\"width\":2221,\"height\":512,\"caption\":\"Semjon Contemporary\"},\"image\":{\"@id\":\"https:\\\/\\\/www.semjoncontemporary.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/semjon\\\/\",\"https:\\\/\\\/www.instagram.com\\\/semjoncontemporary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2019 \u2013 Klaus Steinmann - Semjon Contemporary","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/","og_locale":"en_US","og_type":"article","og_title":"2019 \u2013 Klaus Steinmann - Semjon Contemporary","og_description":"Tafelbild \u2013 BildtafelKlaus Steinmann9.2. \u2013 16.3.2019 Im Grenzbereich der Malerei \u2013 Malerei und Plastik bedingen sich im Werk von Klaus Steinmann In seiner ersten Einzelausstellung bei Semjon Contemporary zeigt Klaus Steinmann Werke der letzten Jahre.Zuvor hatte er 2016 zusammen mit Colin Ardley die Dialogausstellung durchgef\u00fchrt und war 2017 beteiligt an der Galerie-Gruppenausstellung Penetrating Paper: Gebohrt, [&hellip;]","og_url":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/","og_site_name":"Semjon Contemporary","article_publisher":"https:\/\/www.facebook.com\/semjon\/","article_modified_time":"2024-11-12T14:20:39+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2022\/06\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/","url":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/","name":"2019 \u2013 Klaus Steinmann - Semjon Contemporary","isPartOf":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/#primaryimage"},"image":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/#primaryimage"},"thumbnailUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2022\/06\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg","datePublished":"2022-06-06T15:07:13+00:00","dateModified":"2024-11-12T14:20:39+00:00","breadcrumb":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/#primaryimage","url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2022\/06\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg","contentUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2022\/06\/Semjon-Contemporary-Spatial-Strategies-Colin-Ardley-Tafelbild-Bildtafel-Klaus-Steinmann-02182019_083502_Artland_2000.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.semjoncontemporary.com\/2022\/en\/ausstellungen\/bildtafel-tafelbild\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.semjoncontemporary.com\/2022\/"},{"@type":"ListItem","position":2,"name":"2019 \u2013 Klaus Steinmann"}]},{"@type":"WebSite","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#website","url":"https:\/\/www.semjoncontemporary.com\/2022\/","name":"Semjon Contemporary","description":"Galerie f\u00fcr zeitgen\u00f6ssische Kunst","publisher":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.semjoncontemporary.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#organization","name":"Semjon Contemporary","url":"https:\/\/www.semjoncontemporary.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.semjoncontemporary.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/11\/SC-logo.png","contentUrl":"https:\/\/www.semjoncontemporary.com\/2022\/wp-content\/uploads\/2021\/11\/SC-logo.png","width":2221,"height":512,"caption":"Semjon Contemporary"},"image":{"@id":"https:\/\/www.semjoncontemporary.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/semjon\/","https:\/\/www.instagram.com\/semjoncontemporary"]}]}},"_links":{"self":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/ausstellungen\/3924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/ausstellungen"}],"about":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/types\/ausstellungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/media\/3914"}],"wp:attachment":[{"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/media?parent=3924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.semjoncontemporary.com\/2022\/en\/wp-json\/wp\/v2\/categories?post=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}